{"id":1762,"date":"2026-06-02T19:55:06","date_gmt":"2026-06-02T17:55:06","guid":{"rendered":"https:\/\/poetomat.ch\/Wordpress\/?p=1762"},"modified":"2026-06-02T19:56:04","modified_gmt":"2026-06-02T17:56:04","slug":"ich-klicke-also-bin-ich","status":"publish","type":"post","link":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/","title":{"rendered":"Ich klicke, also bin ich"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u00ab\u00dcbrigens\u00bb\u00a0in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie bescheiden die Anforderungen ans Menschsein doch geworden sind, dachte ich neulich, als ich im Internet eine Hose kaufen wollte. \u00abBeweise, dass du ein Mensch bist\u00bb, verlangte die Website von mir. Echt jetzt? Jahrtausendelang haben Philosophinnen, K\u00fcnstler und Wissensschaffende dar\u00fcber gestritten, was uns von Tier und Maschine unterscheidet; und jetzt soll die Antwort lauten: Ich bin ein Mensch, weil ich ein Kreuz neben \u00abIch bin kein Roboter\u00bb setzen kann? Ich klicke, also bin ich?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das sei entmenschlichend, erkl\u00e4rte ich dem netten Herrn vom Kundenservice des Hosenladens, der sich nach einer halben Stunde KI-generierter Panfl\u00f6tenfolter meldete mit \u00abKai Rob Otter, wie kann ich Ihnen helfen?\u00bb. \u00abWieso muss ich einer Maschine beweisen, dass ich keine Maschine bin, indem ich anklicke, dass ich keine Maschine bin?\u00bb \u2013 \u00abReine Sicherheitsmassnahme. Klicken Sie drauf, schon sind sie drin und mit der Hose wieder raus.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abIch weigere mich zu glauben, dass mich das als Mensch ausmacht.\u00bb \u2013 \u00abWas, ein K\u00e4stchen anzuklicken?\u00bb \u2013 \u00abDifferenzierte Feinmotorik, opponierbare Daumen, abstraktes Denken, Selbstreflexion, eine komplexe Sprache, mit der wir uns austauschen k\u00f6nnen \u00fcber Vergangenheit, Zukunft und Blumenkohlrezepte, das macht uns doch als Menschen aus. Wissen, Kunst, Technologie. Und nicht zuletzt Empathie.\u00bb \u00abAha\u00bb, sagte Kai Rob Otter. \u00abGut, Ausnahmen best\u00e4tigen die Regel\u00bb, sagte ich. \u00abWissen Sie, wie satt ich es habe, Bilder mit Fahrr\u00e4dern anzuklicken, nur um dasselbe noch einmal mit Zebrastreifen machen zu m\u00fcssen, weil ich \u00fcbersehen hatte, dass die Fahrradklingel einen Millimeter ins n\u00e4chste Feld hinausragte? Und das alles nur, um eine Hose zu kaufen! Ist das nicht Beweis f\u00fcrs Menschsein genug? Oder haben Sie schon mal einen Bot mit Hosen rumlaufen sehen?\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abKlicken Sie doch einfach auf das Feld\u00bb, kairobotterte es aus dem H\u00f6rer. \u00abKlick dich doch selber\u00bb, w\u00e4re es mir beinahe entfahren. Zum Gl\u00fcck hatte ich Hemmungen. Was uns \u00fcbrigens vom Schimpansen unterscheidet, nicht die glatte Haut oder der fehlende Schwanz. Aber bevor ich Otter mit Matter kommen konnte, sagte Kai Rob: \u00abH\u00f6ren Sie, wenn es Ihnen so gegen den Strich geht, das K\u00e4stchen anzuklicken, dann lassen Sie es halt bleiben.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDas ist es\u00bb, sagte ich. \u00abDer ultimative Beweis f\u00fcr mein Menschsein \u2013 mein freier Wille.\u00bb Ich klickte nicht. Also war ich. Mensch und wunderbar frei. Vor allem untenrum, weil hosenlos. Aber wenigstens hatte ich eine humanistische Erkl\u00e4rung f\u00fcr meine menschliche Bl\u00f6sse.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Bild mit KI generiert<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00dcbrigens\u00bb\u00a0in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026 Wie bescheiden die Anforderungen ans Menschsein doch geworden sind, dachte ich neulich, als ich im Internet eine Hose kaufen wollte. \u00abBeweise, dass du ein Mensch bist\u00bb, verlangte die Website von mir. Echt jetzt? Jahrtausendelang haben Philosophinnen, K\u00fcnstler und Wissensschaffende dar\u00fcber gestritten, was uns von Tier und Maschine &hellip; <a href=\"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/\" class=\"more-link\"><span class=\"screen-reader-text\">Ich klicke, also bin ich<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":1764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ich klicke, also bin ich<\/title>\n<meta name=\"description\" content=\"Wie bescheiden die Anforderungen ans Menschsein doch geworden sind. - \u00ab\u00dcbrigen\u00bb in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ich klicke, also bin ich\" \/>\n<meta property=\"og:description\" content=\"Wie bescheiden die Anforderungen ans Menschsein doch geworden sind. - \u00ab\u00dcbrigen\u00bb in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/\" \/>\n<meta property=\"og:site_name\" content=\"Stephan Moser \u2013 Journalist BR, Kolumnist (Freiburger Nachrichten &amp; Askforce), Autor\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-02T17:55:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T17:56:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1693\" \/>\n\t<meta property=\"og:image:height\" content=\"929\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/#\\\/schema\\\/person\\\/2cc02db160cec37374508657cd9d49a8\"},\"headline\":\"Ich klicke, also bin ich\",\"datePublished\":\"2026-06-02T17:55:06+00:00\",\"dateModified\":\"2026-06-02T17:56:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/\"},\"wordCount\":407,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ChatGPT-Image-2.-Juni-2026-19_53_44.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/\",\"url\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/\",\"name\":\"Ich klicke, also bin ich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ChatGPT-Image-2.-Juni-2026-19_53_44.png\",\"datePublished\":\"2026-06-02T17:55:06+00:00\",\"dateModified\":\"2026-06-02T17:56:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/#\\\/schema\\\/person\\\/2cc02db160cec37374508657cd9d49a8\"},\"description\":\"Wie bescheiden die Anforderungen ans Menschsein doch geworden sind. - \u00ab\u00dcbrigen\u00bb in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ChatGPT-Image-2.-Juni-2026-19_53_44.png\",\"contentUrl\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ChatGPT-Image-2.-Juni-2026-19_53_44.png\",\"width\":1693,\"height\":929},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/ich-klicke-also-bin-ich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ich klicke, also bin ich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/#website\",\"url\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/\",\"name\":\"Stephan Moser \u2013 Journalist BR, Kolumnist (Freiburger Nachrichten &amp; Askforce), Autor\",\"description\":\"Ich bin Journalist, Historiker und Autor. Ich schreibe Kolumnen f\u00fcr die \u00abFreiburger Nachrichten\u00bb und die \u00abAskforce\u00bb. Ich habe f\u00fcr die Musical- und Theaterb\u00fchne geschrieben und arbeite an der Vertonung des Dudens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/#\\\/schema\\\/person\\\/2cc02db160cec37374508657cd9d49a8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4be47fdcfcd0474bbe6a1552cfc76bc6caaa23737fb0bdd2f33684f0f4961c8e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4be47fdcfcd0474bbe6a1552cfc76bc6caaa23737fb0bdd2f33684f0f4961c8e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4be47fdcfcd0474bbe6a1552cfc76bc6caaa23737fb0bdd2f33684f0f4961c8e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/poetomat\"],\"url\":\"https:\\\/\\\/poetomat.ch\\\/Wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ich klicke, also bin ich","description":"Wie bescheiden die Anforderungen ans Menschsein doch geworden sind. - \u00ab\u00dcbrigen\u00bb in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/","og_locale":"de_DE","og_type":"article","og_title":"Ich klicke, also bin ich","og_description":"Wie bescheiden die Anforderungen ans Menschsein doch geworden sind. - \u00ab\u00dcbrigen\u00bb in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026","og_url":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/","og_site_name":"Stephan Moser \u2013 Journalist BR, Kolumnist (Freiburger Nachrichten &amp; Askforce), Autor","article_published_time":"2026-06-02T17:55:06+00:00","article_modified_time":"2026-06-02T17:56:04+00:00","og_image":[{"width":1693,"height":929,"url":"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png","type":"image\/png"}],"author":"admin","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#article","isPartOf":{"@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/"},"author":{"name":"admin","@id":"https:\/\/poetomat.ch\/Wordpress\/#\/schema\/person\/2cc02db160cec37374508657cd9d49a8"},"headline":"Ich klicke, also bin ich","datePublished":"2026-06-02T17:55:06+00:00","dateModified":"2026-06-02T17:56:04+00:00","mainEntityOfPage":{"@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/"},"wordCount":407,"commentCount":0,"image":{"@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#primaryimage"},"thumbnailUrl":"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/","url":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/","name":"Ich klicke, also bin ich","isPartOf":{"@id":"https:\/\/poetomat.ch\/Wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#primaryimage"},"image":{"@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#primaryimage"},"thumbnailUrl":"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png","datePublished":"2026-06-02T17:55:06+00:00","dateModified":"2026-06-02T17:56:04+00:00","author":{"@id":"https:\/\/poetomat.ch\/Wordpress\/#\/schema\/person\/2cc02db160cec37374508657cd9d49a8"},"description":"Wie bescheiden die Anforderungen ans Menschsein doch geworden sind. - \u00ab\u00dcbrigen\u00bb in den \u00abFreiburger Nachrichten\u00bb vom 2. Juni 2026","breadcrumb":{"@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#primaryimage","url":"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png","contentUrl":"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png","width":1693,"height":929},{"@type":"BreadcrumbList","@id":"https:\/\/poetomat.ch\/Wordpress\/ich-klicke-also-bin-ich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/poetomat.ch\/Wordpress\/"},{"@type":"ListItem","position":2,"name":"Ich klicke, also bin ich"}]},{"@type":"WebSite","@id":"https:\/\/poetomat.ch\/Wordpress\/#website","url":"https:\/\/poetomat.ch\/Wordpress\/","name":"Stephan Moser \u2013 Journalist BR, Kolumnist (Freiburger Nachrichten &amp; Askforce), Autor","description":"Ich bin Journalist, Historiker und Autor. Ich schreibe Kolumnen f\u00fcr die \u00abFreiburger Nachrichten\u00bb und die \u00abAskforce\u00bb. Ich habe f\u00fcr die Musical- und Theaterb\u00fchne geschrieben und arbeite an der Vertonung des Dudens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poetomat.ch\/Wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/poetomat.ch\/Wordpress\/#\/schema\/person\/2cc02db160cec37374508657cd9d49a8","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4be47fdcfcd0474bbe6a1552cfc76bc6caaa23737fb0bdd2f33684f0f4961c8e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4be47fdcfcd0474bbe6a1552cfc76bc6caaa23737fb0bdd2f33684f0f4961c8e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4be47fdcfcd0474bbe6a1552cfc76bc6caaa23737fb0bdd2f33684f0f4961c8e?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/x.com\/poetomat"],"url":"https:\/\/poetomat.ch\/Wordpress\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5IsBv-sq","jetpack_featured_media_url":"https:\/\/poetomat.ch\/Wordpress\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-2.-Juni-2026-19_53_44.png","_links":{"self":[{"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/posts\/1762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/comments?post=1762"}],"version-history":[{"count":2,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/posts\/1762\/revisions"}],"predecessor-version":[{"id":1765,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/posts\/1762\/revisions\/1765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/media\/1764"}],"wp:attachment":[{"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/media?parent=1762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/categories?post=1762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poetomat.ch\/Wordpress\/wp-json\/wp\/v2\/tags?post=1762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}